    {"id":22123,"date":"2026-05-18T08:04:53","date_gmt":"2026-05-18T08:04:53","guid":{"rendered":"http:\/\/invercrod.gingenia.com\/?p=22123"},"modified":"2026-03-18T15:43:50","modified_gmt":"2026-03-18T15:43:50","slug":"el-tren-machadiano-campos-de-castilla-inicia-su-2","status":"publish","type":"post","link":"http:\/\/invercrod.gingenia.com\/index.php\/2026\/05\/18\/el-tren-machadiano-campos-de-castilla-inicia-su-2\/","title":{"rendered":"El tren machadiano Campos de Castilla inicia su temporada camino Soria"},"content":{"rendered":"<div id=\"toc\" style=\"background: #f9f9f9;border: 1px solid #aaa;margin-bottom: 1em;padding: 1em;width: 350px\">\n<p class=\"toctitle\" style=\"font-weight: 700;text-align: center\">Content<\/p>\n<ul class=\"toc_list\">\n<li><a href=\"#toc-0\">Ratios y Cuentas anuales de SORIA VACACIONES SL<\/a><\/li>\n<li><a href=\"#toc-1\">Conoce cuanto te costar\u00eda asegurar el cobro de tus facturas a SORIA VACACIONES SL<\/a><\/li>\n<li><a href=\"#toc-3\">Miradores en Soria que debes conocer y visitar<\/a><\/li>\n<li><a href=\"#toc-5\">La Mancomunidad de Tierras Altas instala cinco pantallas t\u00e1ctiles de informaci\u00f3n tur\u00edstica<\/a><\/li>\n<\/ul>\n<\/div>\n<p>Ahora llegaba desde Vallecas para compartir la experiencia con sus descendientes. Para ello, se han preparado diversos paquetes tur\u00edsticos, que se adaptan perfectamente a cualquier viajero. Este a\u00f1o diecis\u00e9is grandes chefs sorianos han incluido en sus cartas y men\u00fas diversos platos protagonizados por la trufa.<\/p>\n<ul>\n<li>Una de las actividades m\u00e1s originales del &#8216;trufiturismo&#8217; para conocer el secreto de la trufa de Soria\u00a0es apuntarse a la &#8216;caza de la trufa negra&#8217;.<\/li>\n<li>\u201d es el lema con el que la Mancomunidad de Tierras Altas de Soria y los Ayuntamientos de Oncala y Las Aldehuelas; que quieren dar a conocer esta experiencia tur\u00edstica \u00fanica.<\/li>\n<li>El tren realizar\u00e1 16 viajes en fin de semana entre los meses de mayo y noviembre.<\/li>\n<\/ul>\n<h2 id=\"toc-0\">Ratios y Cuentas anuales de SORIA VACACIONES SL<\/h2>\n<p>El Tren Campos de Castilla regres\u00f3 ayer a la estaci\u00f3n del Ca\u00f1uelo para recordar el viaje que Antonio Machado realiz\u00f3 entre Madrid y Soria, germen de su poemario \u2018Campos de Castilla\u2019. La estaci\u00f3n de Chamart\u00edn es el punto de partida del viaje, que arranca todos los s\u00e1bados a partir del mes de mayo. Al llegar productos sorianos como los torreznos o la mantequilla dulce y la salada, sirven como aperitivo para dar la bienvenida. La ruta que se realiza, una vez al a\u00f1o, guiando a un reba\u00f1o real de m\u00e1s de 1.000 ovejas trashumantes y con un grupo de pastores en activo, se realizar\u00e1 a finales de junio durante tres d\u00edas. La Mancomunidad de Tierras Altas&nbsp;de Soria, como todos los a\u00f1os, propone una de las experiencias \u00fanicas para conocer el mundo m\u00e1s aut\u00e9ntico y rural. De vuelta a Soria se conocer\u00e1n los restos de la ciudad de Numancia, emblema de la resistencia celt\u00edbera al Imperio Romano.<\/p>\n<h3 id=\"toc-1\">Conoce cuanto te costar\u00eda asegurar el cobro de tus facturas a SORIA VACACIONES SL<\/h3>\n<p>Todo ello acompa\u00f1ado de una degustaci\u00f3n de hasta dos men\u00fas de trufa en restaurantes de Soria. Esta experiencia est\u00e1 disponible durante todo el mes de febrero y hasta el 27 de marzo. Mantequilla de Soria con Denominaci\u00f3n de Origen, Torreznos, Infusiones naturales y vinos de Soria de D.O. El Tren Campos de Castilla, un convoy tur\u00edstico que homenajea a Antonio Machado conectado Madrid y Soria, ya est\u00e1 en marcha en su temporada 2024. Sin olvidarnos del queso de oveja y embutidos de las Tierras Altas sorianas, muy t\u00edpicos y valorados en la zona. El paquete incluye una degustaci\u00f3n de productos t\u00edpicos sorianos, as\u00ed como el traslado y alojamiento una noche en el hotel elegido.<\/p>\n<p>Te llevamos a Soria para conocer la forma de vida de la trashumancia, una experiencia tur\u00edstica y etnogr\u00e1fica \u00fanica. Un viaje a realizar del 8 al <a href=\"soriavacaciones.es\">soriavacaciones.es<\/a> 10 de julio con expertos pastores y un reba\u00f1o de m\u00e1s de 1.000 ovejas merinas. Para ello, Soria Vacaciones ha preparado diversos paquetes tur\u00edsticos que van desde 3 d\u00edas por 175\u20ac o de dos d\u00edas por 75\u20ac.<\/p>\n<h3 id=\"toc-2\">Antonio Naranjo destapa la verdadera raz\u00f3n por la que Sarah Santaolalla mont\u00f3 el numerito en el programa de Nacho Abad<\/h3>\n<p>La agencia Viajes Albur (viajesalbur.net) propone todas ellas durante una escapada guiada de 3 o 4 d\u00edas que recorre Medina del Campo, Olmedo, \u00cdscar&nbsp;y Cu\u00e9llar. Para completar la experiencia (6 \u20ac), nada mejor que hacer una cata con maridaje de productos de la zona. En ella, el visitante podr\u00e1 tener amplia informaci\u00f3n de los valores naturales y culturales de este espacio natural. Es imprescindible atender a las indicaciones del personal del espacio natural, procurando aparcar correctamente, dadas las limitaciones de espacio y los problemas que puede generar.<\/p>\n<h2 id=\"toc-3\">Miradores en Soria que debes conocer y visitar<\/h2>\n<p>Sus platos son todo un espect\u00e1culo, como un escabeche templado de tinta de calamar; trompetillas negras y trufa. Todos estos men\u00fas con trufa que podr\u00e1n ser degustados hasta el 31 de marzo, final de la temporada de este lujoso condimento. Desde hace m\u00e1s de quince a\u00f1os Soria se ha situado entre los mayores productores de trufa en Espa\u00f1a y es un referente de este producto gastron\u00f3mico. El paquete tur\u00edstico completa la experiencia con un recorrido guiado por la Laguna Negra (monumento natural y escenario&nbsp;de \u201cLa tierra de Alvargonz\u00e1lez\u201d) y el yacimiento arqueol\u00f3gico de Numancia.<\/p>\n<h2 id=\"toc-4\">Gu\u00eda para visitar Urue\u00f1a<\/h2>\n<p>Y con la experiencia \u00fanica de dormir dos noches al raso junto a las ovejas en plena Sierra del Alba de Soria y conocer de primera mano el mundo de la trashumancia, una profesi\u00f3n que lamentablemente tiende a desaparecer. La organizaci\u00f3n de tan curioso evento rural ofrece la posibilidad de ser Pastor VIP y hacer el camino con el reba\u00f1o y dormir en casas rurales o alojamientos de la zona. Este personaje, mezcla entre realidad y leyenda, medio literario y medio hist\u00f3rico, naci\u00f3 gracias al escritor soriano Juan Antonio Gaya Nu\u00f1o.<\/p>\n<h3 id=\"toc-5\">La Mancomunidad de Tierras Altas instala cinco pantallas t\u00e1ctiles de informaci\u00f3n tur\u00edstica<\/h3>\n<p>La segunda jornada de este viaje (domingo), el turista realiza el recorrido que hiciera Machado para visitar las Fuentes del Duero y la Laguna Negra. En la temporada 2013 se realizar\u00e1 un homenaje al escritor Juan Antonio Gaya y su &#8216;Santero de San Saturio&#8217;, ya que este a\u00f1o se celebra el centenario de este autor soriano. El viaje se realiza en un tren regular de Renfe que parte de la estaci\u00f3n de Madrid Chamart\u00edn los s\u00e1bados a las 8.14 horas. En el viaje se incluyen otras visitas guiadas por la ciudad, que terminan en el aula de Antonio Machado, que se ha conservado como la dej\u00f3 el poeta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Content Ratios y Cuentas anuales de SORIA VACACIONES SL Conoce cuanto te costar\u00eda asegurar el cobro de tus facturas a SORIA VACACIONES SL Miradores en Soria que debes conocer y visitar La Mancomunidad de Tierras Altas instala cinco pantallas t\u00e1ctiles de informaci\u00f3n tur\u00edstica Ahora llegaba desde Vallecas para compartir la experiencia con sus descendientes. Para &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/invercrod.gingenia.com\/index.php\/2026\/05\/18\/el-tren-machadiano-campos-de-castilla-inicia-su-2\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;El tren machadiano Campos de Castilla inicia su temporada camino Soria&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/invercrod.gingenia.com\/index.php\/wp-json\/wp\/v2\/posts\/22123"}],"collection":[{"href":"http:\/\/invercrod.gingenia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/invercrod.gingenia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/invercrod.gingenia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/invercrod.gingenia.com\/index.php\/wp-json\/wp\/v2\/comments?post=22123"}],"version-history":[{"count":1,"href":"http:\/\/invercrod.gingenia.com\/index.php\/wp-json\/wp\/v2\/posts\/22123\/revisions"}],"predecessor-version":[{"id":22124,"href":"http:\/\/invercrod.gingenia.com\/index.php\/wp-json\/wp\/v2\/posts\/22123\/revisions\/22124"}],"wp:attachment":[{"href":"http:\/\/invercrod.gingenia.com\/index.php\/wp-json\/wp\/v2\/media?parent=22123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/invercrod.gingenia.com\/index.php\/wp-json\/wp\/v2\/categories?post=22123"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/invercrod.gingenia.com\/index.php\/wp-json\/wp\/v2\/tags?post=22123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}